{"id":40,"date":"2023-07-27T08:21:17","date_gmt":"2023-07-27T06:21:17","guid":{"rendered":"https:\/\/frontaliers-grandest.eu\/?page_id=40"},"modified":"2025-07-21T10:04:08","modified_gmt":"2025-07-21T08:04:08","slug":"startseite","status":"publish","type":"page","link":"https:\/\/frontaliers-grandest.eu\/de\/","title":{"rendered":"Startseite"},"content":{"rendered":"\n<h2 class=\"wp-block-heading alignwide has-x-large-font-size\">Unsere Nachrichten<\/h2>\n\n\n    <div class=\"alignwide wp-block-frontaliers-grandest-plugin-frge-actus-slider\">\n        <div class=\"slider-buttons\">\n            <svg stroke-width=\"1\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                class='slider-buttons__prev'>\n                <path d=\"M16 12H8M8 12L11.5 15.5M8 12L11.5 8.5\" stroke-width=\"1\" stroke-linecap=\"round\"\n                    stroke-linejoin=\"round\"><\/path>\n            <\/svg>\n            <svg stroke-width=\"1\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                class='slider-buttons__next'>\n                <path d=\"M8 12H16M16 12L12.5 8.5M16 12L12.5 15.5\" stroke-width=\"1\" stroke-linecap=\"round\"\n                    stroke-linejoin=\"round\"><\/path>\n            <\/svg>\n        <\/div>\n        <div class=\"slider\">\n            <div class=\"swiper swiper-frge-actus\">\n                <div class=\"swiper-wrapper\">\n                                                                                <a class=\"swiper-slide slider__first-card\" href=\"https:\/\/frontaliers-grandest.eu\/de\/steuererklaerung-fuer-deutsche-einkuenfte-in-frankreich\/\">\n                                    <div class=\"slider__first-card--content\">\n                                        <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/woman-working-home-calling-phone-1-scaled.jpg\" class=\"slider__first-card--image wp-post-image\" alt=\"\" srcset=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/woman-working-home-calling-phone-1-scaled.jpg 2560w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/woman-working-home-calling-phone-1-300x200.jpg 300w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/woman-working-home-calling-phone-1-1024x683.jpg 1024w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/woman-working-home-calling-phone-1-768x512.jpg 768w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/woman-working-home-calling-phone-1-1536x1024.jpg 1536w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/woman-working-home-calling-phone-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>                                        <div class=\"image-filter\"><\/div>\n                                        <span class=\"slider__first-card--category\">\n                                            Besteuerung                                        <\/span>\n                                        <span class=\"slider__first-card--title\">\n                                            Steuererkl\u00e4rung f\u00fcr deutsche Eink\u00fcnfte in Frankreich                                        <\/span>\n                                        <p class=\"slider__first-card--excerpt\">\n                                            Bleiben Sie informiert.                                        <\/p>\n                                        <div class=\"slider__first-card--arrow\">\n                                            <svg viewBox=\"0 0 24 24\" stroke-width=\"1\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                                                class='slider__first-card--arrow-icon'>\n                                                <path\n                                                    d=\"M9.17137 9.17157L14.8282 14.8284M14.8282 14.8284H9.87848M14.8282 14.8284V9.87867\"\n                                                    stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                                                <path\n                                                    d=\"M12 22C17.5228 22 22 17.5228 22 12C22 6.47715 17.5228 2 12 2C6.47715 2 2 6.47715 2 12C2 17.5228 6.47715 22 12 22Z\"\n                                                    stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                                            <\/svg>\n                                            <span class=\"view-text\">Nachrichten ansehen<\/span>\n                                        <\/div>\n                                    <\/div>\n                                <\/a>\n                                                                                                                    <a class=\"swiper-slide slider__card\" href=\"https:\/\/frontaliers-grandest.eu\/de\/die-g-bewilligung-fuer-grenzgaenger-in-der-schweiz\/\">\n                                    <div class=\"slider__card--image-container\">\n                                        <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/smiling-businesswoman-reading-data-from-laptop-screen-1-scaled.jpg\" class=\"slider__card--image wp-post-image\" alt=\"\" srcset=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/smiling-businesswoman-reading-data-from-laptop-screen-1-scaled.jpg 2560w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/smiling-businesswoman-reading-data-from-laptop-screen-1-300x200.jpg 300w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/smiling-businesswoman-reading-data-from-laptop-screen-1-1024x683.jpg 1024w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/smiling-businesswoman-reading-data-from-laptop-screen-1-768x512.jpg 768w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/smiling-businesswoman-reading-data-from-laptop-screen-1-1536x1024.jpg 1536w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/smiling-businesswoman-reading-data-from-laptop-screen-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>                                    <\/div>\n                                    <div class=\"slider__card--content\">\n                                        <span class=\"slider__card--date\">\n                                            12\/05\/2026                                        <\/span>\n                                        <span class=\"slider__card--category\">\n                                            Grenzg\u00e4nger                                        <\/span>\n                                        <span class=\"slider__card--title\">\n                                            Die G-Bewilligung f\u00fcr Grenzg\u00e4nger in der Schweiz                                        <\/span>\n                                        <p class=\"slider__card--excerpt\">Gut zu wissen!<\/p>\n                                        <div class=\"slider__card--arrow\">\n                                            <svg viewBox=\"0 0 24 24\" stroke-width=\"1\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                                                class='slider__card--arrow-icon'>\n                                                <path\n                                                    d=\"M9.17137 9.17157L14.8282 14.8284M14.8282 14.8284H9.87848M14.8282 14.8284V9.87867\"\n                                                    stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                                                <path\n                                                    d=\"M12 22C17.5228 22 22 17.5228 22 12C22 6.47715 17.5228 2 12 2C6.47715 2 2 6.47715 2 12C2 17.5228 6.47715 22 12 22Z\"\n                                                    stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                                            <\/svg>\n                                            <span class=\"view-text\">Nachrichten ansehen<\/span>\n                                        <\/div>\n                                    <\/div>\n                                <\/a>\n                                                                                                                    <a class=\"swiper-slide slider__card\" href=\"https:\/\/frontaliers-grandest.eu\/de\/teilzeitarbeitsvertraege-fuer-grenzgaenger-ueberblick-ueber-die-regeln\/\">\n                                    <div class=\"slider__card--image-container\">\n                                        <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/concentrated-male-executive-manager-working-home-2-scaled.jpg\" class=\"slider__card--image wp-post-image\" alt=\"\" srcset=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/concentrated-male-executive-manager-working-home-2-scaled.jpg 2560w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/concentrated-male-executive-manager-working-home-2-300x200.jpg 300w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/concentrated-male-executive-manager-working-home-2-1024x683.jpg 1024w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/concentrated-male-executive-manager-working-home-2-768x512.jpg 768w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/concentrated-male-executive-manager-working-home-2-1536x1024.jpg 1536w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/concentrated-male-executive-manager-working-home-2-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>                                    <\/div>\n                                    <div class=\"slider__card--content\">\n                                        <span class=\"slider__card--date\">\n                                            06\/05\/2026                                        <\/span>\n                                        <span class=\"slider__card--category\">\n                                            Arbeitsrecht                                        <\/span>\n                                        <span class=\"slider__card--title\">\n                                            Teilzeitarbeitsvertr\u00e4ge f\u00fcr Grenzg\u00e4nger \u00dcberblick \u00fcber die Regeln                                        <\/span>\n                                        <p class=\"slider__card--excerpt\">Was man wissen muss<\/p>\n                                        <div class=\"slider__card--arrow\">\n                                            <svg viewBox=\"0 0 24 24\" stroke-width=\"1\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                                                class='slider__card--arrow-icon'>\n                                                <path\n                                                    d=\"M9.17137 9.17157L14.8282 14.8284M14.8282 14.8284H9.87848M14.8282 14.8284V9.87867\"\n                                                    stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                                                <path\n                                                    d=\"M12 22C17.5228 22 22 17.5228 22 12C22 6.47715 17.5228 2 12 2C6.47715 2 2 6.47715 2 12C2 17.5228 6.47715 22 12 22Z\"\n                                                    stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                                            <\/svg>\n                                            <span class=\"view-text\">Nachrichten ansehen<\/span>\n                                        <\/div>\n                                    <\/div>\n                                <\/a>\n                                                                                                                    <a class=\"swiper-slide slider__card\" href=\"https:\/\/frontaliers-grandest.eu\/de\/erklaerung-der-luxemburgischen-einkuenfte-in-frankreich\/\">\n                                    <div class=\"slider__card--image-container\">\n                                        <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/young-woman-checking-her-budget-doing-taxes-1-scaled.jpg\" class=\"slider__card--image wp-post-image\" alt=\"\" srcset=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/young-woman-checking-her-budget-doing-taxes-1-scaled.jpg 2560w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/young-woman-checking-her-budget-doing-taxes-1-300x200.jpg 300w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/young-woman-checking-her-budget-doing-taxes-1-1024x683.jpg 1024w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/young-woman-checking-her-budget-doing-taxes-1-768x512.jpg 768w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/young-woman-checking-her-budget-doing-taxes-1-1536x1024.jpg 1536w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/05\/young-woman-checking-her-budget-doing-taxes-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>                                    <\/div>\n                                    <div class=\"slider__card--content\">\n                                        <span class=\"slider__card--date\">\n                                            04\/05\/2026                                        <\/span>\n                                        <span class=\"slider__card--category\">\n                                            Besteuerung                                        <\/span>\n                                        <span class=\"slider__card--title\">\n                                            Erkl\u00e4rung der luxemburgischen Eink\u00fcnfte in Frankreich                                        <\/span>\n                                        <p class=\"slider__card--excerpt\">Entdecken Sie die wichtigsten Informationen!<\/p>\n                                        <div class=\"slider__card--arrow\">\n                                            <svg viewBox=\"0 0 24 24\" stroke-width=\"1\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                                                class='slider__card--arrow-icon'>\n                                                <path\n                                                    d=\"M9.17137 9.17157L14.8282 14.8284M14.8282 14.8284H9.87848M14.8282 14.8284V9.87867\"\n                                                    stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                                                <path\n                                                    d=\"M12 22C17.5228 22 22 17.5228 22 12C22 6.47715 17.5228 2 12 2C6.47715 2 2 6.47715 2 12C2 17.5228 6.47715 22 12 22Z\"\n                                                    stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                                            <\/svg>\n                                            <span class=\"view-text\">Nachrichten ansehen<\/span>\n                                        <\/div>\n                                    <\/div>\n                                <\/a>\n                                                                                                                    <a class=\"swiper-slide slider__card\" href=\"https:\/\/frontaliers-grandest.eu\/de\/arbeitsvertrag-in-der-schweiz-die-nicht-zu-vergessenden-angaben\/\">\n                                    <div class=\"slider__card--image-container\">\n                                        <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1709\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/04\/two-men-shaking-hands-1-scaled.jpg\" class=\"slider__card--image wp-post-image\" alt=\"\" srcset=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/04\/two-men-shaking-hands-1-scaled.jpg 2560w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/04\/two-men-shaking-hands-1-300x200.jpg 300w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/04\/two-men-shaking-hands-1-1024x683.jpg 1024w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/04\/two-men-shaking-hands-1-768x513.jpg 768w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/04\/two-men-shaking-hands-1-1536x1025.jpg 1536w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/04\/two-men-shaking-hands-1-2048x1367.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>                                    <\/div>\n                                    <div class=\"slider__card--content\">\n                                        <span class=\"slider__card--date\">\n                                            29\/04\/2026                                        <\/span>\n                                        <span class=\"slider__card--category\">\n                                            Arbeit                                        <\/span>\n                                        <span class=\"slider__card--title\">\n                                            Arbeitsvertrag in der Schweiz: die nicht zu vergessenden Angaben                                        <\/span>\n                                        <p class=\"slider__card--excerpt\">Gut zu wissen!<\/p>\n                                        <div class=\"slider__card--arrow\">\n                                            <svg viewBox=\"0 0 24 24\" stroke-width=\"1\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                                                class='slider__card--arrow-icon'>\n                                                <path\n                                                    d=\"M9.17137 9.17157L14.8282 14.8284M14.8282 14.8284H9.87848M14.8282 14.8284V9.87867\"\n                                                    stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                                                <path\n                                                    d=\"M12 22C17.5228 22 22 17.5228 22 12C22 6.47715 17.5228 2 12 2C6.47715 2 2 6.47715 2 12C2 17.5228 6.47715 22 12 22Z\"\n                                                    stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                                            <\/svg>\n                                            <span class=\"view-text\">Nachrichten ansehen<\/span>\n                                        <\/div>\n                                    <\/div>\n                                <\/a>\n                                                                                                                    <a class=\"swiper-slide slider__card\" href=\"https:\/\/frontaliers-grandest.eu\/de\/der-unterschied-zwischen-dem-begriff-des-steuerlichen-wohnsitzes-und-dem-des-verwaltungswohnsitzes\/\">\n                                    <div class=\"slider__card--image-container\">\n                                        <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/04\/corporate-team-joining-forces-create-global-investment-strategy-1-scaled.jpg\" class=\"slider__card--image wp-post-image\" alt=\"\" srcset=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/04\/corporate-team-joining-forces-create-global-investment-strategy-1-scaled.jpg 2560w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/04\/corporate-team-joining-forces-create-global-investment-strategy-1-300x200.jpg 300w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/04\/corporate-team-joining-forces-create-global-investment-strategy-1-1024x683.jpg 1024w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/04\/corporate-team-joining-forces-create-global-investment-strategy-1-768x512.jpg 768w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/04\/corporate-team-joining-forces-create-global-investment-strategy-1-1536x1024.jpg 1536w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2026\/04\/corporate-team-joining-forces-create-global-investment-strategy-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>                                    <\/div>\n                                    <div class=\"slider__card--content\">\n                                        <span class=\"slider__card--date\">\n                                            27\/04\/2026                                        <\/span>\n                                        <span class=\"slider__card--category\">\n                                            Besteuerung                                        <\/span>\n                                        <span class=\"slider__card--title\">\n                                            Der Unterschied zwischen dem Begriff des steuerlichen Wohnsitzes und dem des Verwaltungswohnsitzes                                        <\/span>\n                                        <p class=\"slider__card--excerpt\">Informieren Sie sich.<\/p>\n                                        <div class=\"slider__card--arrow\">\n                                            <svg viewBox=\"0 0 24 24\" stroke-width=\"1\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                                                class='slider__card--arrow-icon'>\n                                                <path\n                                                    d=\"M9.17137 9.17157L14.8282 14.8284M14.8282 14.8284H9.87848M14.8282 14.8284V9.87867\"\n                                                    stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                                                <path\n                                                    d=\"M12 22C17.5228 22 22 17.5228 22 12C22 6.47715 17.5228 2 12 2C6.47715 2 2 6.47715 2 12C2 17.5228 6.47715 22 12 22Z\"\n                                                    stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                                            <\/svg>\n                                            <span class=\"view-text\">Nachrichten ansehen<\/span>\n                                        <\/div>\n                                    <\/div>\n                                <\/a>\n                                                                                <a class=\"swiper-slide slider__card--last\" href=\"https:\/\/frontaliers-grandest.eu\/de\/nachricht\/\">\n                            <div class=\" slider__card--last--content-last\">\n                                <svg viewBox=\"0 0 24 24\" stroke-width=\"1\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                                    class='slider__card--last--arrow-icon'>\n                                    <path d=\"M9.17137 9.17157L14.8282 14.8284M14.8282 14.8284H9.87848M14.8282 14.8284V9.87867\"\n                                        stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                                    <path\n                                        d=\"M12 22C17.5228 22 22 17.5228 22 12C22 6.47715 17.5228 2 12 2C6.47715 2 2 6.47715 2 12C2 17.5228 6.47715 22 12 22Z\"\n                                        stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                                <\/svg>\n                                <span\n                                    class=\"slider__card--last-link\">Alle Nachrichten anzeigen<\/span>\n                            <\/div>\n                        <\/a>\n                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n    \n\n\n<div class=\"wp-block-cover alignfull frge-question-pattern\"><img decoding=\"async\" class=\"wp-block-cover__image-background wp-image-75\" alt=\"\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/themes\/frontaliers-grandest\/src\/img\/question-pattern-background.jpg\" data-object-fit=\"cover\"\/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group alignwide has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/themes\/frontaliers-grandest\/src\/img\/question-icon.png\" alt=\"\" class=\"wp-image-251\" style=\"width:252px;height:auto\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h2 class=\"wp-block-heading has-large-font-size\">Eine Frage?<\/h2>\n\n\n\n<p>Eine Frage zum Thema Grenzarbeit. Unser Team von Juristen steht Ihnen gerne zur Verf\u00fcgung, wenn Sie Informationen zum Arbeitsrecht, zur Sozialversicherung oder zur Besteuerung von Grenzg\u00e4ngern ben\u00f6tigen.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-medium-font-size has-custom-font-size wp-element-button\" href=\"https:\/\/frontaliers-grandest.eu\/de\/ueber-frontaliers-grand-est\/contact\/\">Kontaktieren Sie uns<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-frontaliers-grandest-plugin-frge-infos-slider alignfull\"><div class=\"infos-group alignfull is-layout-constrained\"><div class=\"infos-container alignwide\"><h2 class=\"infos-container__title\">N\u00fctzliche Infos<\/h2><div class=\"infos-container__top\"><div class=\"infos-container__navigation\"><svg stroke-width=\"1\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"infos-container__prev-button\"><path d=\"M16 12H8M8 12L11.5 15.5M8 12L11.5 8.5\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><svg stroke-width=\"1\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"infos-container__next-button\"><path d=\"M8 12H16M16 12L12.5 8.5M16 12L12.5 15.5\" stroke-width=\"1\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/div><\/div><div class=\"swiper swiper-infos-slider\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide infos-slide\"><div class=\"infos-container__slide-content\"><span class=\"infos-container__slide-title\" style=\"display:none\">Veranstaltungen<\/span><a style=\"height:100%;width:100%;border-radius:10px;overflow:hidden;position:relative\" href=\"https:\/\/frontaliers-grandest.eu\/de\/veranstaltungen\/\" class=\"infos-container__slide-content-link\"><div class=\"infos-container__img-filter\"><\/div><div class=\"infos-container__img-render\"><span class=\"infos-container__img-render--title\">Veranstaltungen<\/span><img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/2025_03_28_Moovijob-divers_037.jpg\" class=\"infos-container__img\" loading=\"lazy\" srcset=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/2025_03_28_Moovijob-divers_037-150x150.jpg 150w,https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/2025_03_28_Moovijob-divers_037-300x200.jpg 300w,https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/2025_03_28_Moovijob-divers_037-1024x683.jpg 1024w,https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/2025_03_28_Moovijob-divers_037.jpg 1620w,\" width=\"1620\" height=\"1080\" alt=\"\" sizes=\"auto, (max-width: 1620px) 100vw, 1620px\"\/><\/div><\/a><\/div><\/div><div class=\"swiper-slide infos-slide\"><div class=\"infos-container__slide-content\"><span class=\"infos-container__slide-title\" style=\"display:none\">Rente<\/span><a style=\"height:100%;width:100%;border-radius:10px;overflow:hidden;position:relative\" href=\"https:\/\/frontaliers-grandest.eu\/de\/startseite\/rente\/\" class=\"infos-container__slide-content-link\"><div class=\"infos-container__img-filter\"><\/div><div class=\"infos-container__img-render\"><span class=\"infos-container__img-render--title\">Rente<\/span><img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/vecteezy_ai-generated-woman-in-the-office-posing-with-her-arms-crossed_36779527-scaled.jpg\" class=\"infos-container__img\" loading=\"lazy\" srcset=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/vecteezy_ai-generated-woman-in-the-office-posing-with-her-arms-crossed_36779527-150x150.jpg 150w,https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/vecteezy_ai-generated-woman-in-the-office-posing-with-her-arms-crossed_36779527-300x122.jpg 300w,https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/vecteezy_ai-generated-woman-in-the-office-posing-with-her-arms-crossed_36779527-1024x417.jpg 1024w,https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/vecteezy_ai-generated-woman-in-the-office-posing-with-her-arms-crossed_36779527-scaled.jpg 2560w,\" width=\"2560\" height=\"1043\" alt=\"\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\"\/><\/div><\/a><\/div><\/div><div class=\"swiper-slide infos-slide\"><div class=\"infos-container__slide-content\"><span class=\"infos-container__slide-title\" style=\"display:none\">Fremdsprachen<\/span><a style=\"height:100%;width:100%;border-radius:10px;overflow:hidden;position:relative\" href=\"https:\/\/frontaliers-grandest.eu\/de\/startseite\/fremdsprachen-lernen\/\" class=\"infos-container__slide-content-link\"><div class=\"infos-container__img-filter\"><\/div><div class=\"infos-container__img-render\"><span class=\"infos-container__img-render--title\">Fremdsprachen<\/span><img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/vecteezy_books-on-the-table-in-the-library-education-learning-old_7764661-scaled.jpg\" class=\"infos-container__img\" loading=\"lazy\" srcset=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/vecteezy_books-on-the-table-in-the-library-education-learning-old_7764661-150x150.jpg 150w,https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/vecteezy_books-on-the-table-in-the-library-education-learning-old_7764661-300x200.jpg 300w,https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/vecteezy_books-on-the-table-in-the-library-education-learning-old_7764661-1024x684.jpg 1024w,https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/vecteezy_books-on-the-table-in-the-library-education-learning-old_7764661-scaled.jpg 2560w,\" width=\"2560\" height=\"1709\" alt=\"\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\"\/><\/div><\/a><\/div><\/div><div class=\"swiper-slide infos-slide\"><div class=\"infos-container__slide-content\"><span class=\"infos-container__slide-title\" style=\"display:none\">FAQ<\/span><a style=\"height:100%;width:100%;border-radius:10px;overflow:hidden;position:relative\" href=\"https:\/\/frontaliers-grandest.eu\/de\/faq\/\" class=\"infos-container__slide-content-link\"><div class=\"infos-container__img-filter\"><\/div><div class=\"infos-container__img-render\"><span class=\"infos-container__img-render--title\">FAQ<\/span><img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/vecteezy_wooden-blocks-circles-with-word-frequently-asked_7664479-scaled.jpg\" class=\"infos-container__img\" loading=\"lazy\" srcset=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/vecteezy_wooden-blocks-circles-with-word-frequently-asked_7664479-150x150.jpg 150w,https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/vecteezy_wooden-blocks-circles-with-word-frequently-asked_7664479-300x177.jpg 300w,https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/vecteezy_wooden-blocks-circles-with-word-frequently-asked_7664479-1024x604.jpg 1024w,https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/vecteezy_wooden-blocks-circles-with-word-frequently-asked_7664479-scaled.jpg 2560w,\" width=\"2560\" height=\"1511\" alt=\"\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\"\/><\/div><\/a><\/div><\/div><div class=\"swiper-slide infos-slide\"><div class=\"infos-container__slide-content\"><span class=\"infos-container__slide-title\" style=\"display:none\">TRANSPORTE<\/span><a style=\"height:100%;width:100%;border-radius:10px;overflow:hidden;position:relative\" href=\"https:\/\/frontaliers-grandest.eu\/de\/startseite\/transporte\/\" class=\"infos-container__slide-content-link\"><div class=\"infos-container__img-filter\"><\/div><div class=\"infos-container__img-render\"><span class=\"infos-container__img-render--title\">TRANSPORTE<\/span><img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/young-asian-woman-backpacker-traveler-walking-alone-train-station-platform-with-backpack-scaled.jpg\" class=\"infos-container__img\" loading=\"lazy\" srcset=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/young-asian-woman-backpacker-traveler-walking-alone-train-station-platform-with-backpack-150x150.jpg 150w,https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/young-asian-woman-backpacker-traveler-walking-alone-train-station-platform-with-backpack-300x200.jpg 300w,https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/young-asian-woman-backpacker-traveler-walking-alone-train-station-platform-with-backpack-1024x683.jpg 1024w,https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/young-asian-woman-backpacker-traveler-walking-alone-train-station-platform-with-backpack-scaled.jpg 2560w,\" width=\"2560\" height=\"1707\" alt=\"\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\"\/><\/div><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading alignwide has-x-large-font-size\">Unser Team<\/h2>\n\n\n    <div class=\"is-layout-constrained alignfull wp-block-frontaliers-grandest-plugin-frge-teams-slider\">\n        <div class=\"block-background alignfull\"><\/div>\n        <div class=\"alignwide\" style=\"box-sizing: border-box;\">\n            <div class=\"slider-teams-buttons\">\n                <svg stroke-width=\"1\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                    class='slider-teams-buttons__prev'>\n                    <path d=\"M16 12H8M8 12L11.5 15.5M8 12L11.5 8.5\" stroke-width=\"1\" stroke-linecap=\"round\"\n                        stroke-linejoin=\"round\"><\/path>\n                <\/svg>\n                <svg stroke-width=\"1\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                    class='slider-teams-buttons__next'>\n                    <path d=\"M8 12H16M16 12L12.5 8.5M16 12L12.5 15.5\" stroke-width=\"1\" stroke-linecap=\"round\"\n                        stroke-linejoin=\"round\"><\/path>\n                <\/svg>\n            <\/div>\n            <div class=\"slider\">\n                <div class=\"swiper swiper-frge-teams\">\n                    <div class=\"swiper-wrapper\">\n                                                        <div class=\"swiper-slide slider__card\">\n                                    <div class=\"slider__card--names\">\n                                                                                    <span class=\"slider__card--name\">\n                                                Julien                                            <\/span>\n                                            <span class=\"slider__card--lastname\">\n                                                DAUER                                            <\/span>\n                                                                            <\/div>\n                                    <div class=\"slider__card--image-container\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2024\/02\/CRD-8535_Julien-scaled.jpg\"\n                                                alt=\"Picture of JulienDAUER\"\n                                                loading=\"lazy\" \/>\n                                                                            <\/div>\n                                    <div class=\"slider__card--content\">\n                                        <div class=\"slider__card--description\">\n                                            <span class=\"slider__card--function\">\n                                                Leiter                                            <\/span>\n                                            <p class=\"slider__card--languages\">\n                                                Informiert Sie auf Deutsch, English und Franz\u00f6sisch                                            <\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"swiper-slide slider__card\">\n                                    <div class=\"slider__card--names\">\n                                                                                    <span class=\"slider__card--name\">\n                                                Cl\u00e9lia                                            <\/span>\n                                            <span class=\"slider__card--lastname\">\n                                                MARTIN                                            <\/span>\n                                                                            <\/div>\n                                    <div class=\"slider__card--image-container\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/04\/CRD-8524_Clelia-scaled.jpg\"\n                                                alt=\"Picture of Cl\u00e9liaMARTIN\"\n                                                loading=\"lazy\" \/>\n                                                                            <\/div>\n                                    <div class=\"slider__card--content\">\n                                        <div class=\"slider__card--description\">\n                                            <span class=\"slider__card--function\">\n                                                Leiter der Rechtsabteilung                                             <\/span>\n                                            <p class=\"slider__card--languages\">\n                                                Informiert Sie auf Deutsch, English und Franz\u00f6sisch                                            <\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"swiper-slide slider__card\">\n                                    <div class=\"slider__card--names\">\n                                                                                    <span class=\"slider__card--name\">\n                                                Alice                                            <\/span>\n                                            <span class=\"slider__card--lastname\">\n                                                RAGUCCIA                                            <\/span>\n                                                                            <\/div>\n                                    <div class=\"slider__card--image-container\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/04\/CRD-8460-Alice-scaled.jpg\"\n                                                alt=\"Picture of AliceRAGUCCIA\"\n                                                loading=\"lazy\" \/>\n                                                                            <\/div>\n                                    <div class=\"slider__card--content\">\n                                        <div class=\"slider__card--description\">\n                                            <span class=\"slider__card--function\">\n                                                Senior Jurist                                            <\/span>\n                                            <p class=\"slider__card--languages\">\n                                                informiert Sie aud English und Franz\u00f6sich                                            <\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"swiper-slide slider__card\">\n                                    <div class=\"slider__card--names\">\n                                                                                    <span class=\"slider__card--name\">\n                                                Souad                                            <\/span>\n                                            <span class=\"slider__card--lastname\">\n                                                Ben Bouazza                                            <\/span>\n                                                                            <\/div>\n                                    <div class=\"slider__card--image-container\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/10\/Photo-Souad-2.png\"\n                                                alt=\"Picture of SouadBen Bouazza\"\n                                                loading=\"lazy\" \/>\n                                                                            <\/div>\n                                    <div class=\"slider__card--content\">\n                                        <div class=\"slider__card--description\">\n                                            <span class=\"slider__card--function\">\n                                                Juristin                                            <\/span>\n                                            <p class=\"slider__card--languages\">\n                                                Informiert Sie auf English und Franz\u00f6sisch                                            <\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"swiper-slide slider__card\">\n                                    <div class=\"slider__card--names\">\n                                                                                    <span class=\"slider__card--name\">\n                                                Mahaut                                            <\/span>\n                                            <span class=\"slider__card--lastname\">\n                                                CREMEL                                            <\/span>\n                                                                            <\/div>\n                                    <div class=\"slider__card--image-container\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/04\/CRD-8468_Mahaut-scaled.jpg\"\n                                                alt=\"Picture of MahautCREMEL\"\n                                                loading=\"lazy\" \/>\n                                                                            <\/div>\n                                    <div class=\"slider__card--content\">\n                                        <div class=\"slider__card--description\">\n                                            <span class=\"slider__card--function\">\n                                                Juristin                                            <\/span>\n                                            <p class=\"slider__card--languages\">\n                                                Informiert Sie auf English und Franz\u00f6sisch                                            <\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"swiper-slide slider__card\">\n                                    <div class=\"slider__card--names\">\n                                                                                    <span class=\"slider__card--name\">\n                                                Nadia                                            <\/span>\n                                            <span class=\"slider__card--lastname\">\n                                                SLILA                                            <\/span>\n                                                                            <\/div>\n                                    <div class=\"slider__card--image-container\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/04\/CRD-8477_Nadia-scaled.jpg\"\n                                                alt=\"Picture of NadiaSLILA\"\n                                                loading=\"lazy\" \/>\n                                                                            <\/div>\n                                    <div class=\"slider__card--content\">\n                                        <div class=\"slider__card--description\">\n                                            <span class=\"slider__card--function\">\n                                                Digital Manager                                            <\/span>\n                                            <p class=\"slider__card--languages\">\n                                                Informiert Sie auf Deutsch, English und Franz\u00f6sisch                                            <\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"swiper-slide slider__card\">\n                                    <div class=\"slider__card--names\">\n                                                                                    <span class=\"slider__card--name\">\n                                                Celena                                            <\/span>\n                                            <span class=\"slider__card--lastname\">\n                                                MATEOS                                            <\/span>\n                                                                            <\/div>\n                                    <div class=\"slider__card--image-container\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/04\/CRD-8514-Celena-scaled.jpg\"\n                                                alt=\"Picture of CelenaMATEOS\"\n                                                loading=\"lazy\" \/>\n                                                                            <\/div>\n                                    <div class=\"slider__card--content\">\n                                        <div class=\"slider__card--description\">\n                                            <span class=\"slider__card--function\">\n                                                Beauftragte f\u00fcr Kommunikation und Marketing                                            <\/span>\n                                            <p class=\"slider__card--languages\">\n                                                informiert Sie aud English und Franz\u00f6sich                                             <\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"swiper-slide slider__card\">\n                                    <div class=\"slider__card--names\">\n                                                                                    <span class=\"slider__card--name\">\n                                                Sandrine                                            <\/span>\n                                            <span class=\"slider__card--lastname\">\n                                                SCHWABE                                            <\/span>\n                                                                            <\/div>\n                                    <div class=\"slider__card--image-container\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/04\/CRD-8446_Sandrine-scaled.jpg\"\n                                                alt=\"Picture of SandrineSCHWABE\"\n                                                loading=\"lazy\" \/>\n                                                                            <\/div>\n                                    <div class=\"slider__card--content\">\n                                        <div class=\"slider__card--description\">\n                                            <span class=\"slider__card--function\">\n                                                Buchhaltungssekret\u00e4rin                                            <\/span>\n                                            <p class=\"slider__card--languages\">\n                                                Informiert Sie auf Deutsch, English und Franz\u00f6sisch                                            <\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"swiper-slide slider__card\">\n                                    <div class=\"slider__card--names\">\n                                                                                    <span class=\"slider__card--name\">\n                                                Safa                                            <\/span>\n                                            <span class=\"slider__card--lastname\">\n                                                MOUKADIM                                            <\/span>\n                                                                            <\/div>\n                                    <div class=\"slider__card--image-container\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/09\/photo-site-safa-1-scaled.png\"\n                                                alt=\"Picture of SafaMOUKADIM\"\n                                                loading=\"lazy\" \/>\n                                                                            <\/div>\n                                    <div class=\"slider__card--content\">\n                                        <div class=\"slider__card--description\">\n                                            <span class=\"slider__card--function\">\n                                                Kommunikationsstudentin im dualen Studium                                            <\/span>\n                                            <p class=\"slider__card--languages\">\n                                                Informiert Sie auf Franz\u00f6sisch und Englisch                                             <\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"swiper-slide slider__card\">\n                                    <div class=\"slider__card--names\">\n                                                                                    <span class=\"slider__card--name\">\n                                                Lara                                            <\/span>\n                                            <span class=\"slider__card--lastname\">\n                                                FICHTNER                                            <\/span>\n                                                                            <\/div>\n                                    <div class=\"slider__card--image-container\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/09\/lara-recadrer-scaled.png\"\n                                                alt=\"Picture of LaraFICHTNER\"\n                                                loading=\"lazy\" \/>\n                                                                            <\/div>\n                                    <div class=\"slider__card--content\">\n                                        <div class=\"slider__card--description\">\n                                            <span class=\"slider__card--function\">\n                                                Juristin im dualen Studium                                            <\/span>\n                                            <p class=\"slider__card--languages\">\n                                                Informiert Sie auf Franz\u00f6sisch, Deutsch und Englisch                                             <\/p>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n    \n\n    <div class=\"alignfull wp-block-frontaliers-grandest-plugin-frge-funders-slider\">\n        <div class=\"slider-funders-container alignwide\" style=\"background-color: #F0F1F3;\">\n            <h2 class=\"funder-block-title\">Unsere Finanzpartner<\/h2>\n            <div class='slider-funders-buttons'>\n                <svg stroke-width=\"1\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                    class='slider-funders-buttons__prev'>\n                    <path d=\"M16 12H8M8 12L11.5 15.5M8 12L11.5 8.5\" stroke-width=\"1\" stroke-linecap=\"round\"\n                        stroke-linejoin=\"round\"><\/path>\n                <\/svg>\n                <svg stroke-width=\"1\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                    class='slider-funders-buttons__next'>\n                    <path d=\"M8 12H16M16 12L12.5 8.5M16 12L12.5 15.5\" stroke-width=\"1\" stroke-linecap=\"round\"\n                        stroke-linejoin=\"round\"><\/path>\n                <\/svg>\n            <\/div>\n            <div class=\"slider\">\n                <div class=\"swiper swiper-frge-funders\">\n                    <div class=\"swiper-wrapper\">\n                                                            <a class=\"swiper-slide slider__card\"\n                                        href=\"https:\/\/www.grandest.fr\/\">\n                                                                            <div class=\"slider__img-container\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"388\" height=\"130\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2024\/02\/logo-grand-est.png\" class=\"slider__img\" alt=\"Logo R\u00e9gion Grand Est\" \/>                                        <\/div>\n                                                                            <\/a>\n                                                                                            <a class=\"swiper-slide slider__card\"\n                                        href=\"https:\/\/commission.europa.eu\/index_de\">\n                                                                            <div class=\"slider__img-container\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"195\" height=\"135\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2024\/02\/commission-europe.png\" class=\"slider__img\" alt=\"Commission Europ\u00e9enne\" \/>                                        <\/div>\n                                                                            <\/a>\n                                                                                            <a class=\"swiper-slide slider__card\"\n                                        href=\"https:\/\/www.linkedin.com\/company\/lim-ex-france-wallonie-vlaanderen\/posts\/?feedView=all\">\n                                                                            <div class=\"slider__img-container\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1587\" height=\"739\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/12\/logo-lim-ex-jpeg.jpg\" class=\"slider__img\" alt=\"\" srcset=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/12\/logo-lim-ex-jpeg.jpg 1587w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/12\/logo-lim-ex-jpeg-300x140.jpg 300w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/12\/logo-lim-ex-jpeg-1024x477.jpg 1024w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/12\/logo-lim-ex-jpeg-768x358.jpg 768w, https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/12\/logo-lim-ex-jpeg-1536x715.jpg 1536w\" sizes=\"auto, (max-width: 1587px) 100vw, 1587px\" \/>                                        <\/div>\n                                                                            <\/a>\n                                                                                            <a class=\"swiper-slide slider__card\"\n                                        href=\"https:\/\/www.iba-oie.eu\/\">\n                                                                            <div class=\"slider__img-container\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2024\/02\/logo_IBA_OIE_kurz.png\" class=\"slider__img\" alt=\"OBSERVATOIRE INTERR\u00c9GIONAL DE L\u2019EMPLOI\" \/>                                        <\/div>\n                                                                            <\/a>\n                                                                                            <a class=\"swiper-slide slider__card\"\n                                        href=\"https:\/\/www.cd08.fr\/\">\n                                                                            <div class=\"slider__img-container\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"192\" height=\"108\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2024\/02\/ardennes.png\" class=\"slider__img\" alt=\"\" \/>                                        <\/div>\n                                                                            <\/a>\n                                                                                            <a class=\"swiper-slide slider__card\"\n                                        href=\"https:\/\/ardenne-metropole.fr\/\">\n                                                                            <div class=\"slider__img-container\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"853\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2024\/02\/ARDENNE-LOGO-CMJN-scaled-1.jpg\" class=\"slider__img\" alt=\"\" \/>                                        <\/div>\n                                                                            <\/a>\n                                                                                            <a class=\"swiper-slide slider__card\"\n                                        href=\"https:\/\/www.portesduluxembourg.fr\/\">\n                                                                            <div class=\"slider__img-container\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"320\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2024\/02\/Porte-du-luxembourg-logo-quadri.jpg\" class=\"slider__img\" alt=\"Logo communaut\u00e9 de communes portes du luxembourg\" \/>                                        <\/div>\n                                                                            <\/a>\n                                                                                            <a class=\"swiper-slide slider__card\"\n                                        href=\"https:\/\/www.cc-valleesetplateaudardenne.fr\/\">\n                                                                            <div class=\"slider__img-container\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"109\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2024\/02\/Logo-JPEG_ComCom_ValleesPlateauArdenne_OK-scaled-e1630490848330.jpg\" class=\"slider__img\" alt=\"Communaut\u00e9 de Communes Vall\u00e9es et Plateau d&#039;Ardenne\" \/>                                        <\/div>\n                                                                            <\/a>\n                                                                                            <a class=\"swiper-slide slider__card\"\n                                        href=\"https:\/\/www.ccarm.fr\/\">\n                                                                            <div class=\"slider__img-container\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1530\" height=\"1550\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2024\/02\/nouveau-logo-CCARMjpeg.jpg\" class=\"slider__img\" alt=\"Communaut\u00e9 de communes Ardenne Rives de Meuse\" \/>                                        <\/div>\n                                                                            <\/a>\n                                                                                            <a class=\"swiper-slide slider__card\"\n                                        href=\"https:\/\/www.ardennes-thierache.com\/fr\/\">\n                                                                            <div class=\"slider__img-container\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"318\" height=\"240\" src=\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2024\/02\/Logo-Ardennes-Thierache.png\" class=\"slider__img\" alt=\"Communaut\u00e9 de communes Ardennes Thi\u00e9rarche\" \/>                                        <\/div>\n                                                                            <\/a>\n                                                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n    <\/div>\n    ","protected":false},"excerpt":{"rendered":"<p>Unsere Nachrichten Unser Team<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"tags":[],"frge_profile":[],"class_list":["post-40","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Startseite - Frontaliers Grand Est<\/title>\n<meta name=\"description\" content=\"Frontaliers Grand Est bietet juristische Informationen \u00fcber das Grenzg\u00e4ngerstatus in der Grossregion und in der Region Grand Est.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frontaliers-grandest.eu\/de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Startseite - Frontaliers Grand Est\" \/>\n<meta property=\"og:description\" content=\"Frontaliers Grand Est bietet juristische Informationen \u00fcber das Grenzg\u00e4ngerstatus in der Grossregion und in der Region Grand Est.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frontaliers-grandest.eu\/de\/\" \/>\n<meta property=\"og:site_name\" content=\"Frontaliers Grand Est\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frontaliers.GR.EST\/?locale=fr_FR\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-21T08:04:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frontaliers-grandest.eu\/wp-content\/themes\/frontaliers-grandest\/src\/img\/question-pattern-background.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/frontaliers-grandest.eu\/de\/\",\"url\":\"https:\/\/frontaliers-grandest.eu\/de\/\",\"name\":\"Startseite - Frontaliers Grand Est\",\"isPartOf\":{\"@id\":\"https:\/\/frontaliers-grandest.eu\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/frontaliers-grandest.eu\/de\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/frontaliers-grandest.eu\/de\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/frontaliers-grandest.eu\/wp-content\/themes\/frontaliers-grandest\/src\/img\/question-pattern-background.jpg\",\"datePublished\":\"2023-07-27T06:21:17+00:00\",\"dateModified\":\"2025-07-21T08:04:08+00:00\",\"description\":\"Frontaliers Grand Est bietet juristische Informationen \u00fcber das Grenzg\u00e4ngerstatus in der Grossregion und in der Region Grand Est.\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/frontaliers-grandest.eu\/de\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/frontaliers-grandest.eu\/de\/#primaryimage\",\"url\":\"https:\/\/frontaliers-grandest.eu\/wp-content\/themes\/frontaliers-grandest\/src\/img\/question-pattern-background.jpg\",\"contentUrl\":\"https:\/\/frontaliers-grandest.eu\/wp-content\/themes\/frontaliers-grandest\/src\/img\/question-pattern-background.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/frontaliers-grandest.eu\/de\/#website\",\"url\":\"https:\/\/frontaliers-grandest.eu\/de\/\",\"name\":\"Frontaliers Grand Est\",\"description\":\"Le site ressource du travail frontalier\",\"publisher\":{\"@id\":\"https:\/\/frontaliers-grandest.eu\/de\/#organization\"},\"alternateName\":\"Frontaliers Grand Est\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/frontaliers-grandest.eu\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/frontaliers-grandest.eu\/de\/#organization\",\"name\":\"Frontaliers Grand Est\",\"alternateName\":\"Frontaliers Grand Est\",\"url\":\"https:\/\/frontaliers-grandest.eu\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/frontaliers-grandest.eu\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/260328234_2966785176920310_3332838526503858160_n.jpg\",\"contentUrl\":\"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/260328234_2966785176920310_3332838526503858160_n.jpg\",\"width\":396,\"height\":396,\"caption\":\"Frontaliers Grand Est\"},\"image\":{\"@id\":\"https:\/\/frontaliers-grandest.eu\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/frontaliers.GR.EST\/?locale=fr_FR\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Startseite - Frontaliers Grand Est","description":"Frontaliers Grand Est bietet juristische Informationen \u00fcber das Grenzg\u00e4ngerstatus in der Grossregion und in der Region Grand Est.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frontaliers-grandest.eu\/de\/","og_locale":"de_DE","og_type":"article","og_title":"Startseite - Frontaliers Grand Est","og_description":"Frontaliers Grand Est bietet juristische Informationen \u00fcber das Grenzg\u00e4ngerstatus in der Grossregion und in der Region Grand Est.","og_url":"https:\/\/frontaliers-grandest.eu\/de\/","og_site_name":"Frontaliers Grand Est","article_publisher":"https:\/\/www.facebook.com\/frontaliers.GR.EST\/?locale=fr_FR","article_modified_time":"2025-07-21T08:04:08+00:00","og_image":[{"url":"https:\/\/frontaliers-grandest.eu\/wp-content\/themes\/frontaliers-grandest\/src\/img\/question-pattern-background.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/frontaliers-grandest.eu\/de\/","url":"https:\/\/frontaliers-grandest.eu\/de\/","name":"Startseite - Frontaliers Grand Est","isPartOf":{"@id":"https:\/\/frontaliers-grandest.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frontaliers-grandest.eu\/de\/#primaryimage"},"image":{"@id":"https:\/\/frontaliers-grandest.eu\/de\/#primaryimage"},"thumbnailUrl":"https:\/\/frontaliers-grandest.eu\/wp-content\/themes\/frontaliers-grandest\/src\/img\/question-pattern-background.jpg","datePublished":"2023-07-27T06:21:17+00:00","dateModified":"2025-07-21T08:04:08+00:00","description":"Frontaliers Grand Est bietet juristische Informationen \u00fcber das Grenzg\u00e4ngerstatus in der Grossregion und in der Region Grand Est.","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frontaliers-grandest.eu\/de\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/frontaliers-grandest.eu\/de\/#primaryimage","url":"https:\/\/frontaliers-grandest.eu\/wp-content\/themes\/frontaliers-grandest\/src\/img\/question-pattern-background.jpg","contentUrl":"https:\/\/frontaliers-grandest.eu\/wp-content\/themes\/frontaliers-grandest\/src\/img\/question-pattern-background.jpg"},{"@type":"WebSite","@id":"https:\/\/frontaliers-grandest.eu\/de\/#website","url":"https:\/\/frontaliers-grandest.eu\/de\/","name":"Frontaliers Grand Est","description":"Le site ressource du travail frontalier","publisher":{"@id":"https:\/\/frontaliers-grandest.eu\/de\/#organization"},"alternateName":"Frontaliers Grand Est","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frontaliers-grandest.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/frontaliers-grandest.eu\/de\/#organization","name":"Frontaliers Grand Est","alternateName":"Frontaliers Grand Est","url":"https:\/\/frontaliers-grandest.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/frontaliers-grandest.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/260328234_2966785176920310_3332838526503858160_n.jpg","contentUrl":"https:\/\/frontaliers-grandest.eu\/wp-content\/uploads\/2025\/07\/260328234_2966785176920310_3332838526503858160_n.jpg","width":396,"height":396,"caption":"Frontaliers Grand Est"},"image":{"@id":"https:\/\/frontaliers-grandest.eu\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/frontaliers.GR.EST\/?locale=fr_FR"]}]}},"frge_page_order":0,"_links":{"self":[{"href":"https:\/\/frontaliers-grandest.eu\/de\/wp-json\/wp\/v2\/pages\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frontaliers-grandest.eu\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/frontaliers-grandest.eu\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/frontaliers-grandest.eu\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/frontaliers-grandest.eu\/de\/wp-json\/wp\/v2\/comments?post=40"}],"version-history":[{"count":182,"href":"https:\/\/frontaliers-grandest.eu\/de\/wp-json\/wp\/v2\/pages\/40\/revisions"}],"predecessor-version":[{"id":50816,"href":"https:\/\/frontaliers-grandest.eu\/de\/wp-json\/wp\/v2\/pages\/40\/revisions\/50816"}],"wp:attachment":[{"href":"https:\/\/frontaliers-grandest.eu\/de\/wp-json\/wp\/v2\/media?parent=40"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frontaliers-grandest.eu\/de\/wp-json\/wp\/v2\/tags?post=40"},{"taxonomy":"frge_profile","embeddable":true,"href":"https:\/\/frontaliers-grandest.eu\/de\/wp-json\/wp\/v2\/frge_profile?post=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}